{"id":7430,"date":"2019-06-14T01:26:37","date_gmt":"2019-06-14T04:26:37","guid":{"rendered":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/?p=7430"},"modified":"2019-06-14T01:32:26","modified_gmt":"2019-06-14T04:32:26","slug":"red-neuronal-artificial-entrenada-para-crear-tipos","status":"publish","type":"post","link":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/red-neuronal-artificial-entrenada-para-crear-tipos\/","title":{"rendered":"Red neuronal artificial entrenada para crear tipos"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Esta serie de experimentos tipogr\u00e1ficos innovadores ampl\u00eda nuestra comprensi\u00f3n del papel que la tecnolog\u00eda puede desempe\u00f1ar en el dise\u00f1o de tipos.<\/h3>\n\n\n\n<p>Erik Bernhardsson,&nbsp;un\nex ingeniero de Spotify, que actualmente trabaja en Better, realiz\u00f3 un\nexperimento en el cual recopilo 50.000 fuentes de toda la web con el objetivo\nde usar este conjunto de datos masivo para entrenar una red neuronal para crear\nnuevos caracteres y fuentes.<\/p>\n\n\n\n<p style=\"text-align:left\">En el primer experimento le pidi\u00f3 a la red neuronal que completara un caracter faltante usando solo su conocimiento de las otras letras y su entrenamiento, produjo un caracter que pens\u00f3 que encajar\u00eda mejor con la fuente, en algunos casos fue precisa. La red neuronal sab\u00eda casi exactamente qu\u00e9 determinaci\u00f3n tendr\u00eda una &#8220;d&#8221; min\u00fascula para una fuente sans-serif con una sombra, por ejemplo, como sucede en la quinta fila de abajo de la siguiente imagen (en cada ejemplo, la letra real est\u00e1 a la izquierda, mientras que la mejor estimaci\u00f3n de la red neuronal a la derecha).<\/p>\n\n\n\n<ul class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"596\" height=\"596\" data-attachment-id=\"7431\" data-permalink=\"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/red-neuronal-artificial-entrenada-para-crear-tipos\/imagen-1-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-content\/uploads\/2019\/06\/imagen-1-1.jpg?fit=596%2C596&amp;ssl=1\" data-orig-size=\"596,596\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"imagen-1-1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-content\/uploads\/2019\/06\/imagen-1-1.jpg?fit=596%2C596&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-content\/uploads\/2019\/06\/imagen-1-1.jpg?resize=596%2C596&#038;ssl=1\" alt=\"\" data-id=\"7431\" data-link=\"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/?attachment_id=7431\" class=\"wp-image-7431\" srcset=\"https:\/\/i0.wp.com\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-content\/uploads\/2019\/06\/imagen-1-1.jpg?w=596&amp;ssl=1 596w, https:\/\/i0.wp.com\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-content\/uploads\/2019\/06\/imagen-1-1.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-content\/uploads\/2019\/06\/imagen-1-1.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-content\/uploads\/2019\/06\/imagen-1-1.jpg?resize=55%2C55&amp;ssl=1 55w\" sizes=\"auto, (max-width: 596px) 100vw, 596px\" \/><\/figure><\/li><\/ul>\n\n\n\n<p><em>&#8220;El modelo ha visto otros caracter de la misma fuente durante el entrenamiento, as\u00ed que lo que hace es inferir de esos ejemplos de entrenamiento a los ejemplos de pruebas invisibles&#8221;<\/em> explica Erik. <\/p>\n\n\n\n<p>Posterior a\nesto Erik le pidi\u00f3 a la red neuronal que realizara un promedio de cada tipo de\nletra en el que se hab\u00eda entrenado, lo que resulto ser esta fuente arquet\u00edpica de enfoque suave que se muestra a\ncontinuaci\u00f3n:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" data-attachment-id=\"7432\" data-permalink=\"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/red-neuronal-artificial-entrenada-para-crear-tipos\/imagen-2-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-content\/uploads\/2019\/06\/Imagen-2-1.png?fit=640%2C640&amp;ssl=1\" data-orig-size=\"640,640\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Imagen-2-1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-content\/uploads\/2019\/06\/Imagen-2-1.png?fit=640%2C640&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-content\/uploads\/2019\/06\/Imagen-2-1.png?resize=640%2C640&#038;ssl=1\" alt=\"\" class=\"wp-image-7432\" srcset=\"https:\/\/i0.wp.com\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-content\/uploads\/2019\/06\/Imagen-2-1.png?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-content\/uploads\/2019\/06\/Imagen-2-1.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-content\/uploads\/2019\/06\/Imagen-2-1.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-content\/uploads\/2019\/06\/Imagen-2-1.png?resize=55%2C55&amp;ssl=1 55w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p>Luego, el promedio se redujo a la mitad\nde cada caracter para crear una interpretaci\u00f3n m\u00e1s legible y s\u00f3lida de la\nestructura del signo como se muestra a continuaci\u00f3n:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" data-attachment-id=\"7433\" data-permalink=\"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/red-neuronal-artificial-entrenada-para-crear-tipos\/imagen-3-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-content\/uploads\/2019\/06\/Imagen-3-1.png?fit=512%2C512&amp;ssl=1\" data-orig-size=\"512,512\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Imagen-3-1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-content\/uploads\/2019\/06\/Imagen-3-1.png?fit=512%2C512&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-content\/uploads\/2019\/06\/Imagen-3-1.png?resize=512%2C512&#038;ssl=1\" alt=\"\" class=\"wp-image-7433\" srcset=\"https:\/\/i0.wp.com\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-content\/uploads\/2019\/06\/Imagen-3-1.png?w=512&amp;ssl=1 512w, https:\/\/i0.wp.com\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-content\/uploads\/2019\/06\/Imagen-3-1.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-content\/uploads\/2019\/06\/Imagen-3-1.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-content\/uploads\/2019\/06\/Imagen-3-1.png?resize=55%2C55&amp;ssl=1 55w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure>\n\n\n\n<p>En otro\nexperimento le pidi\u00f3 a la red neuronal que creara una fuente totalmente nueva\nbasada en un vector aleatorio del conjunto de entrenamiento, como resultado de\nello una serie de fuentes basada en el conocimiento pasado de la red neuronal.<\/p>\n\n\n\n<ul class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><li class=\"blocks-gallery-item\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"311\" data-attachment-id=\"7434\" data-permalink=\"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/red-neuronal-artificial-entrenada-para-crear-tipos\/gif-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-content\/uploads\/2019\/06\/Gif-1.gif?fit=636%2C311&amp;ssl=1\" data-orig-size=\"636,311\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Gif-1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-content\/uploads\/2019\/06\/Gif-1.gif?fit=636%2C311&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-content\/uploads\/2019\/06\/Gif-1.gif?resize=636%2C311&#038;ssl=1\" alt=\"\" data-id=\"7434\" data-link=\"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/?attachment_id=7434\" class=\"wp-image-7434\" \/><\/figure><\/li><\/ul>\n\n\n\n<p>Erik explica <em>&#8220;Como cada fuente es un vector, podemos crear vectores de fuente arbitrarios y generar resultados a partir de ella.\u00a0Podemos elegir un vector de fuente y generar nuevas fuentes a partir de perturbaciones aleatorias. Tambi\u00e9n podemos generar fuentes completamente nuevas.\u00a0Si modelamos la distribuci\u00f3n de vectores de fuentes como una multivariable normal, podemos muestrear vectores aleatorios de ella y observar las fuentes que generan\u201d<\/em>.<\/p>\n\n\n\n<p>Eso es lo que podemos ver en el gif de\narriba. Se sabe, por ejemplo, que muchas fuentes utilizan may\u00fasculas para el\nconjunto de min\u00fasculas, y cambia de forma inteligente entre las dos dependiendo\ndel tipo de fuente que est\u00e9 creando<\/p>\n\n\n\n<p>En conclusi\u00f3n, esto no es<strong> \u201cdise\u00f1o tipogr\u00e1fico\u201d<\/strong> sino m\u00e1s bien una creaci\u00f3n generativa por deducci\u00f3n, cabe destacar que no deja de ser un experimento interesante. Las redes neuronales podr\u00edan no hacerse cargo del trabajo de los dise\u00f1adores todav\u00eda, pero es un proyecto muy bueno que demuestra lo que pueden ser.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta serie de experimentos tipogr\u00e1ficos innovadores ampl\u00eda nuestra comprensi\u00f3n del papel que la tecnolog\u00eda puede desempe\u00f1ar en el dise\u00f1o de tipos. Erik Bernhardsson,&nbsp;un ex ingeniero de Spotify, que actualmente trabaja en Better, realiz\u00f3 un experimento en el cual recopilo 50.000 fuentes de toda la web con el objetivo de usar este conjunto de datos masivo [&hellip;]<\/p>\n","protected":false},"author":259,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Red neuronal artificial entrenada para crear tipos  #\u200eTipoblog #Tipograf&iacute;a2 #C&aacute;tedraCosgaya #\u200eFADU #\u200eUBA","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[27,34],"tags":[],"class_list":["post-7430","post","type-post","status-publish","format-standard","hentry","category-educacion","category-tecnologia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paXRK8-1VQ","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-json\/wp\/v2\/posts\/7430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-json\/wp\/v2\/users\/259"}],"replies":[{"embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-json\/wp\/v2\/comments?post=7430"}],"version-history":[{"count":6,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-json\/wp\/v2\/posts\/7430\/revisions"}],"predecessor-version":[{"id":7440,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-json\/wp\/v2\/posts\/7430\/revisions\/7440"}],"wp:attachment":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-json\/wp\/v2\/media?parent=7430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-json\/wp\/v2\/categories?post=7430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-json\/wp\/v2\/tags?post=7430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}