{"id":7118,"date":"2019-05-31T13:38:59","date_gmt":"2019-05-31T16:38:59","guid":{"rendered":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/?p=7118"},"modified":"2019-05-31T13:39:09","modified_gmt":"2019-05-31T16:39:09","slug":"waltograph","status":"publish","type":"post","link":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/waltograph\/","title":{"rendered":"Waltograph"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hace unos d\u00edas me habl\u00f3 una mam\u00e1 para pedirme que haga unas invitaciones para el cumplea\u00f1os de su hijo. En el mensaje, entre otras indicaciones me puso, \u201cy que tenga la letra de Disney\u201d. \u00a0Obviamente hubiera elegido otra tipograf\u00eda, pero eso me hizo preguntarme \u00bfCu\u00e1l es la historia de esa tipograf\u00eda? <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-content\/uploads\/2019\/05\/walt-disney-1.png?w=640&#038;ssl=1\" alt=\"\" class=\"wp-image-7122\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Todos habremos visto la tipograf\u00eda de Disney alguna vez: \u201cWalt\nDisney\u201d, el fondo azul, el castillo. &nbsp;E investigando\ndescubr\u00ed que llama Waltograph, y que se bas\u00f3 en una versi\u00f3n estilizada del\naut\u00f3grafo de Walt Disney. Este logotipo ha tenido varias versiones desde el\noriginal, algunas bajo su t\u00edtulo original de &#8220;Walt Disney Script&#8221;, lanzado\npor primera vez en el 2000. Walt Disney Script se actualiz\u00f3 continuamente y\nfinalmente se cambi\u00f3 su nombre a Waltograph en 2004.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y pensando me di cuenta que por m\u00e1s que sea una tipograf\u00eda \u201codiada\u201d\npor los dise\u00f1adores gr\u00e1ficos, tiene su historia, y tiene su l\u00f3gica: la compa\u00f1\u00eda\nDisney se basa en la creatividad, la fantas\u00eda, \u201clos sue\u00f1os hechos realidad\u201d, y\nsu tipograf\u00eda refleja eso. Con sus formas bucleadas y gestos espont\u00e1neos, el\npunto de la i, la manualidad que tiene; expresa muy bien esa creatividad y esa\nmagia que transmite Disney. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, tiene mucho poder de identificaci\u00f3n. Si yo veo esa tipograf\u00eda en cualquier lugar externo a Disney, voy a identificarla como \u201cla letra de Disney\u201d de la misma forma que \u00e9sta mama me dijo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En conclusi\u00f3n, Waltograph, \u201cla letra de Disney\u201d (la cual probablemente use para esta invitaci\u00f3n de cumplea\u00f1os y nunca m\u00e1s) es una especie de Comic Sans, evitada por los dise\u00f1adores pero todos siempre vamos a reconocerla al instante y eso es una gran virtud para una tipograf\u00eda. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace unos d\u00edas me habl\u00f3 una mam\u00e1 para pedirme que haga unas invitaciones para el cumplea\u00f1os de su hijo. En el mensaje, entre otras indicaciones me puso, \u201cy que tenga la letra de Disney\u201d. \u00a0Obviamente hubiera elegido otra tipograf\u00eda, pero eso me hizo preguntarme \u00bfCu\u00e1l es la historia de esa tipograf\u00eda? Todos habremos visto la [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":7125,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Waltograph  #\u200eTipoblog #Tipograf&iacute;a2 #C&aacute;tedraCosgaya #\u200eFADU #\u200eUBA","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[26],"tags":[79,48,78],"class_list":["post-7118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-disney","tag-tipografia","tag-waltograph"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-content\/uploads\/2019\/05\/walt-disney-1.png?fit=620%2C350&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paXRK8-1QO","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-json\/wp\/v2\/posts\/7118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-json\/wp\/v2\/comments?post=7118"}],"version-history":[{"count":4,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-json\/wp\/v2\/posts\/7118\/revisions"}],"predecessor-version":[{"id":7129,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-json\/wp\/v2\/posts\/7118\/revisions\/7129"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-json\/wp\/v2\/media\/7125"}],"wp:attachment":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-json\/wp\/v2\/media?parent=7118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-json\/wp\/v2\/categories?post=7118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2019\/wp-json\/wp\/v2\/tags?post=7118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}