{"id":4682,"date":"2015-09-09T01:25:33","date_gmt":"2015-09-09T01:25:33","guid":{"rendered":"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/?p=4682"},"modified":"2015-09-09T01:25:33","modified_gmt":"2015-09-09T01:25:33","slug":"en-busca-de-la-minerva-y-su-sistema-de-impresion","status":"publish","type":"post","link":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/en-busca-de-la-minerva-y-su-sistema-de-impresion\/","title":{"rendered":"En busca de la Minerva y su sistema de impresi\u00f3n."},"content":{"rendered":"<p>Como si se tratara de un viaje gradual al pasado, la impresi\u00f3n artesanal con tipos m\u00f3viles viene ganando terreno.<br \/>\nIntroducirse a este mundo es algo \u00fanico. Esas personas que dedicaron toda su vida a este oficio, abren las puerta de sus talleres para mostrarles al resto de las personas su mundo, ese mundo m\u00e1gico del imprentero.<br \/>\nEn Argentina cada vez son m\u00e1s las imprentas que bajan sus puertas, pero hay algo que surge, personas que combinan la impresi\u00f3n tradicional y las nuevas tecnolog\u00edas.<\/p>\n<p>La era digital no pudo contra las imprentas tipogr\u00e1ficas, que resisten en talleres inspiradores donde verdaderos artistas se especializan en dise\u00f1ar y producir piezas gr\u00e1ficas de modo artesanal combin\u00e1ndolo con\u00a0tecnolog\u00eda actual.<\/p>\n<p>El llamado letterpress o en espa\u00f1ol impresi\u00f3n tipogr\u00e1fica,\u00a0no solo tiene que resolverse con tipos m\u00f3viles existentes, haciendo uso de programas de computaci\u00f3n, la t\u00e9cnica puede mezclarse con la tecnolog\u00eda donde el arte trazado\u00a0<span style=\"line-height: 1.5\">se pueden traducir a una placa de zinc fotograbada logrando reproducir logotipos o im\u00e1genes de tipo vectorial, el efecto de relieve es el mismo, y la ventaja es que, a diferencia de los tipos m\u00f3viles, aqu\u00ed no hay limitaciones tipogr\u00e1ficas ni de composici\u00f3n.<\/span><\/p>\n<p>Este sistema de impresi\u00f3n nos da otra calidad por su materialidad, que se suele utilizar papeles artesanales de 100% algod\u00f3n, papeles especiales y gramaje grueso.<\/p>\n<p>Esta materialidad es un medio importante por el cual podemos transmitir una primera sensaci\u00f3n al usuario, la materialidad y el m\u00e9todo de impresi\u00f3n hace que el sistema sea mas rico y \u00fanicos, el letterpress permite esto, texto en relieve, o bajo relieve que tiene como recurso interesante el uso del mismo soporte para general el elemento gr\u00e1fico, y aparte de un aporte t\u00e1ctil fuerte.\u00a0Los papeles artesanales, la tipograf\u00eda, las prensas, las tintas, las texturas\u2026son los elementos\u00a0que genera un sistema \u00fanico y distintivo.<\/p>\n<p>Comienza con el dise\u00f1o, que se convierte en metal para llegar a la prensa, una cl\u00e1sica Chandler &amp; Price de 1890. Luego se mezcla la tinta, se entinta el plato, se elige el papel, se ajusta la impresi\u00f3n corrigiendo errores y finalmente se imprime&#8230;<br \/>\nUna imagen que pod\u00e9s sentir, tocar, percibir el relieve, la forma, la profundidad&#8230; Un papel grueso, con relieve, trama, con humedad y olor a algod\u00f3n&#8230; Tinta rica, espesa y org\u00e1nica&#8230; .<br \/>\nLetterpress es nuevo y viejo a la vez, es el revival de lo tradicional potenciado con dise\u00f1o moderno. Y adem\u00e1s&#8230; \u00a1es lindo!<\/p>\n<p><a href=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/09\/Wilkintie-letterpress-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4691\" src=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/09\/Wilkintie-letterpress-1-300x200.jpg\" alt=\"Wilkintie-letterpress-1\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/09\/Wilkintie-letterpress-1-300x200.jpg 300w, https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/09\/Wilkintie-letterpress-1.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/09\/letterpress-boris.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4690\" src=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/09\/letterpress-boris-300x200.jpg\" alt=\"letterpress-boris\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/09\/letterpress-boris-300x200.jpg 300w, https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/09\/letterpress-boris.jpg 715w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> \u00a0<a href=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/09\/Blind_debossed_letterpress_business_card.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4688\" src=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/09\/Blind_debossed_letterpress_business_card-300x186.jpg\" alt=\"Blind_debossed_letterpress_business_card\" width=\"300\" height=\"186\" srcset=\"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/09\/Blind_debossed_letterpress_business_card-300x186.jpg 300w, https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/09\/Blind_debossed_letterpress_business_card.jpg 650w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4689\" src=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/09\/blue-and-red-letterpress-300x152.jpg\" alt=\"blue-and-red-letterpress\" width=\"300\" height=\"152\" srcset=\"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/09\/blue-and-red-letterpress-300x152.jpg 300w, https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/09\/blue-and-red-letterpress.jpg 965w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como si se tratara de un viaje gradual al pasado, la impresi\u00f3n artesanal con tipos m\u00f3viles viene ganando terreno. Introducirse a este mundo es algo \u00fanico. Esas personas que dedicaron toda su vida a este [&hellip;]<\/p>\n","protected":false},"author":129,"featured_media":4685,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[21],"tags":[],"class_list":["post-4682","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sistemas"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/09\/tumblr_m8k93mRzRf1rohtj2o2_1280.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6gfAF-1dw","_links":{"self":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/posts\/4682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/users\/129"}],"replies":[{"embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/comments?post=4682"}],"version-history":[{"count":9,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/posts\/4682\/revisions"}],"predecessor-version":[{"id":4697,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/posts\/4682\/revisions\/4697"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/media\/4685"}],"wp:attachment":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/media?parent=4682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/categories?post=4682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/tags?post=4682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}