{"id":4563,"date":"2015-08-31T13:21:08","date_gmt":"2015-08-31T13:21:08","guid":{"rendered":"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/?p=4563"},"modified":"2015-08-31T19:22:48","modified_gmt":"2015-08-31T19:22:48","slug":"como-organizarme-ante-la-informacion-y-no-desesperar-en-el-intento","status":"publish","type":"post","link":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/como-organizarme-ante-la-informacion-y-no-desesperar-en-el-intento\/","title":{"rendered":"C\u00f3mo organizarme ante la informaci\u00f3n y no desesperar en el intento."},"content":{"rendered":"<p>La escasez del mismo ante una fecha determinada para entregar y los miles de factores que nos acontecen d\u00eda a d\u00eda me hizo pensar que, una buena organizaci\u00f3n tiene que ser el aliado fundamental para evitar nuestra tan com\u00fan crisis de desesperaci\u00f3n y la frase: \u201cmam\u00e1 no llego, qu\u00e9 hago? (inserte comentarios de desesperaci\u00f3n aqu\u00ed)\u201d.<\/p>\n<p>El planteo de este trabajo pr\u00e1ctico es, a grandes rasgos, poder que recopilar informaci\u00f3n sobre un determinado tema, diagramarla y plasmarla de forma gr\u00e1fica en un sistema de informaci\u00f3n con tantas piezas como queramos. Se sum\u00f3\u00a0una te\u00f3rica que planteaba seis pasos para la organizaci\u00f3n de la informaci\u00f3n y creo que esos seis pasos van perfectamente acompa\u00f1ados de la organizaci\u00f3n del tiempo. Pero entonces, \u00bfc\u00f3mo puedo fusionar mi tiempo y la organizaci\u00f3n de la informaci\u00f3n? Yendo desde lo macro hasta lo micro.<\/p>\n<p>Combinando distintos tipos de organizaciones temporales podemos enfocarnos en casi todos los puntos.<\/p>\n<ul>\n<li>Desde un punto de vista global, plantear las tareas a realizar en la totalidad del proyecto es una buena manera de empezar. Existe un diagrama que se llama \u201cdiagrama de Gantt\u201d. Es una pieza de organizaci\u00f3n que consta de: la totalidad de tareas del proyecto, la duraci\u00f3n de las mismas y la fecha estimada de realizaci\u00f3n de ellas. \u00a0\u00abGantt\u00bb proporciona el <em>status<\/em> actual del proyecto , lo cual permite la proyecci\u00f3n de cambios a futuro,si es que los hubiese.<\/li>\n<\/ul>\n<figure id=\"attachment_4564\" aria-describedby=\"caption-attachment-4564\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/08\/gantt.gif\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4564\" src=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/08\/gantt-1024x546.gif\" alt=\"Diagrama utilizado para la planificaci\u00f3n de tiempo.\" width=\"600\" height=\"320\" srcset=\"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/08\/gantt-1024x546.gif 1024w, https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/08\/gantt-300x160.gif 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-4564\" class=\"wp-caption-text\">Diagrama utilizado para la planificaci\u00f3n de tiempo.<\/figcaption><\/figure>\n<ul>\n<li>Desde un punto de vista m\u00e1s cercano, por ejemplo las tareas a realizar en el d\u00eda, existe un m\u00e9todo que se llama \u201c<em>Pomodoro Technique<\/em>\u201d. Esta es una t\u00e9cnica que plantea tiempos cortos de trabajo (25 minutos) y un descanso (5\/10 minutos). Las tareas realizadas y la cantidad de tiempo (\u00ab<em>pomodoros<\/em>\u00ab) que nos llev\u00f3 completarlas se plasman en una tablita. Este m\u00e9todo busca perfeccionar el tiempo de ejecuci\u00f3n de cada tarea.<\/li>\n<\/ul>\n<p>Si bien creo que existe una forma de organizaci\u00f3n por cada persona, hay m\u00e9todos desarrollados por otros que nos pueden ayudar a nosotros a llegar a nuestras entregas y, en particular, a poder desarrollar el trabajo pr\u00e1ctico en curso explotando al m\u00e1ximo cada mil\u00e9sima de segundo que tenemos hasta la \u00faltima clase.<\/p>\n<p>Estos son dos modos de ver la organizaci\u00f3n del tiempo. \u00a0Realmente, poder verlo como un aliado y hacer un panorama general de c\u00f3mo trabajar creo que es la mejor manera de encarar este, y todos los trabajos pr\u00e1cticos que nos quedan por delante.<\/p>\n<p>Les dejo una bonita pieza que dibuj\u00e9 para que lo recuerden.<\/p>\n<p><a href=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/08\/tiempo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4570 size-medium\" src=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/08\/tiempo-300x300.jpg\" alt=\"tiempo\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/08\/tiempo-300x300.jpg 300w, https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/08\/tiempo-150x150.jpg 150w, https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/08\/tiempo.jpg 825w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Fuentes:<\/p>\n<p>\u00abPomodoro Technique\u00bb: <a href=\"http:\/\/www.pomodorotechnique.com\">http:\/\/www.pomodorotechnique.com<\/a><\/p>\n<p>Para ampliar el uso del diagrama de Gantt dejo un link <a href=\"https:\/\/www.youtube.com\/watch?v=KRFet8XlFyg\" target=\"_blank\">aqu\u00ed<\/a>.<\/p>\n<p>Im\u00e1genes: Diagrama de Gantt (Proporcionado por google)\u00a0. Lettering (Camulina.-)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando se hizo el lanzamiento oficial del trabajo pr\u00e1ctico de sistemas y escuch\u00e9 la palabra complejidad una de las primeras palabras que se me vino a la mente fue: tiempo. <\/p>\n","protected":false},"author":113,"featured_media":4567,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[21],"tags":[183,23,22,211],"class_list":["post-4563","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sistemas","tag-informacion","tag-organizacion","tag-sistemas-2","tag-tiempo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/08\/printer.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6gfAF-1bB","_links":{"self":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/posts\/4563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/users\/113"}],"replies":[{"embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/comments?post=4563"}],"version-history":[{"count":13,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/posts\/4563\/revisions"}],"predecessor-version":[{"id":4579,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/posts\/4563\/revisions\/4579"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/media\/4567"}],"wp:attachment":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/media?parent=4563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/categories?post=4563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/tags?post=4563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}