{"id":4448,"date":"2015-08-25T22:25:48","date_gmt":"2015-08-25T22:25:48","guid":{"rendered":"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/?p=4448"},"modified":"2015-08-25T22:25:48","modified_gmt":"2015-08-25T22:25:48","slug":"la-potencia-visual-de-los-sistemas-graficos","status":"publish","type":"post","link":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/la-potencia-visual-de-los-sistemas-graficos\/","title":{"rendered":"La potencia visual de los sistemas gr\u00e1ficos"},"content":{"rendered":"<p>Un sistema gr\u00e1fico es una serie de piezas, cada una con un objetivo particular, pero todas respondiendo a un objetivo total. Las piezas pueden cumplir funciones aisladas, pero para cumplir con el objetivo total deben estar todas presentes. Comparten una coherencia formal y funcional.<\/p>\n<p><a href=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/08\/sistema.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4456\" src=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/08\/sistema-300x200.jpg\" alt=\"sistema\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/08\/sistema-300x200.jpg 300w, https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/08\/sistema.jpg 736w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Colocar un mismo logo \u00fanicamente en todas las piezas no es suficiente como para que se entienda f\u00e1cilmente que \u00abjuegan en el mismo equipo\u00bb.<\/p>\n<p>Para generar un buen sistema gr\u00e1fico se debe pensar en un criterio tipogr\u00e1fico, espec\u00edfico, as\u00ed tambi\u00e9n como en \u00a0un criterio de color, de estructuraci\u00f3n y de uso de las im\u00e1genes para que todos los elementos se vean unificados, sin ser iguales ni ser repeticiones. Formando de esta manera un conjunto de constantes y variables que permiten demostrar que estamos hablando de lo mismo. As\u00ed el poder de las im\u00e1genes para comunicar y difundir se multiplicar\u00e1, logrando mejores resultados.<\/p>\n<p><a href=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/08\/sistemas5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4459\" src=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/08\/sistemas5-238x300.jpg\" alt=\"sistemas5\" width=\"238\" height=\"300\" srcset=\"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/08\/sistemas5-238x300.jpg 238w, https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/08\/sistemas5.jpg 600w\" sizes=\"auto, (max-width: 238px) 100vw, 238px\" \/><\/a><\/p>\n<p>La complejidad de los mensajes para comunicar, sumada a la cantidad \u00a0de funciones que deben cumplir las piezas gr\u00e1fica, hace que sea imposible que una sola pieza pueda cumplir con todos los requisitos, por esto se distribuyen los diversos recursos de la comunicaci\u00f3n en distintos elementos gr\u00e1ficos, formando de esta manera un sistema.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201c Un sistema es m\u00e1s que una simple suma de partes, son las partes, sus funciones individuales y sus relaciones intr\u00ednsecas. \u201d Karl Gerstner<\/p>\n","protected":false},"author":106,"featured_media":4458,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[21],"tags":[],"class_list":["post-4448","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sistemas"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/08\/sistemas4.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6gfAF-19K","_links":{"self":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/posts\/4448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/users\/106"}],"replies":[{"embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/comments?post=4448"}],"version-history":[{"count":2,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/posts\/4448\/revisions"}],"predecessor-version":[{"id":4461,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/posts\/4448\/revisions\/4461"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/media\/4458"}],"wp:attachment":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/media?parent=4448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/categories?post=4448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/tags?post=4448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}