{"id":3866,"date":"2015-07-02T03:16:08","date_gmt":"2015-07-02T03:16:08","guid":{"rendered":"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/?p=3866"},"modified":"2015-07-02T03:16:08","modified_gmt":"2015-07-02T03:16:08","slug":"viva-la-nostalgia","status":"publish","type":"post","link":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/viva-la-nostalgia\/","title":{"rendered":"Viva la Nostalgia"},"content":{"rendered":"<p>\u00bfQue es un tocadiscos? Es un equipo de audio que extrae y amplifica el sonido contenido en el disco. Este tiene una pua que recorre la superficie grabada, reproduciendo as\u00ed, vibraciones inscriptas en el LP. Esta se\u00f1al es amplificada posteriormente.<\/p>\n<p><a href=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/07\/enhanced-buzz-30552-1380138880-17.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-3871 aligncenter\" src=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/07\/enhanced-buzz-30552-1380138880-17-300x297.jpg\" alt=\"enhanced-buzz-30552-1380138880-17\" width=\"300\" height=\"297\" srcset=\"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/07\/enhanced-buzz-30552-1380138880-17-300x297.jpg 300w, https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/07\/enhanced-buzz-30552-1380138880-17-150x150.jpg 150w, https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/07\/enhanced-buzz-30552-1380138880-17.jpg 625w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Para su \u00e9poca de origen, era un objeto de gran tecnolog\u00eda, algo vital y cotidiano en el hogar, ahora, un tocadiscos es toda una antig\u00fcedad. Sin embargo, todo lo \u00abviejo\u00bb se renueva.\u00a0Como ya muchos expusieron en posteos anteriores, en la actualidad existe una observaci\u00f3n por volver a los viejos tiempos. Se toman antig\u00fcedades y se las renuevan, convirti\u00e9ndolas en piezas de dise\u00f1o, sin perder la esencia de las mismas. Obviamente el tocadiscos no escapo de esta tendencia. Fue el grupo <em><strong>Gramovox<\/strong><\/em> el que decidi\u00f3 buscarle la vuelta al asunto y, tomando las partes originales del mismo, crearon el <em><strong>Floatyng Record<\/strong><\/em>. Si bien sigue siendo un tocadiscos, este reproduce los LP en posici\u00f3n vertical, combinando as\u00ed un dise\u00f1o vintage con uno\u00a0tecnol\u00f3gico.<\/p>\n<p><a href=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/07\/3307eac68bce64e71afa1f5343da8c32_original.gif\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-3888 aligncenter\" src=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/07\/3307eac68bce64e71afa1f5343da8c32_original-300x200.gif\" alt=\"3307eac68bce64e71afa1f5343da8c32_original\" width=\"300\" height=\"200\" \/><\/a><\/p>\n<p>Este tocadiscos suplanta el plato original por un brazo de fibra de carbono exclusivamente dise\u00f1ado para sujetar los discos correctamente. Este brazo esta equilibrado en torno a su principal eje de soporte, apoyado de forma din\u00e1mica sobre un resorte, lo cual mantiene la p\u00faa en el eje del disco. El Floating Recod los voltea en un angulo de 90 grados para reproducirlos, logrando de esta forma un efecto de \u00abflotaci\u00f3n\u00bb. Este innovador equipo de m\u00fasica, cuenta con <em>altavoces de rango completo<\/em> y con una entrada para auriculares.<\/p>\n<p><a href=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/07\/a90934c693cb95e40ddfa43e9e81caf5_original.jpg\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3892 aligncenter\" src=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/07\/a90934c693cb95e40ddfa43e9e81caf5_original-300x200.jpg\" alt=\"a90934c693cb95e40ddfa43e9e81caf5_original\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/07\/a90934c693cb95e40ddfa43e9e81caf5_original-300x200.jpg 300w, https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/07\/a90934c693cb95e40ddfa43e9e81caf5_original.jpg 680w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\u00a0 \u00a0 \u00a0 \u00a0<\/a><\/p>\n<p>Sus creadores son oriundos de Chicago y fueron conocidos por haber creado el primer <strong><em>Gram\u00f3fono Bluetooh<\/em><\/strong> en el 2013 y, si bien, el Floating Record todav\u00eda esta buscando financiaci\u00f3n en <em>Kickstarter<\/em>, ya pasaron su meta de 50 mil dolares. Por lo visto <em><strong>Gramovox<\/strong><\/em> seguir\u00e1 creando maneras creativas de escuchar m\u00fasica en alta fidelidad con un toque de nostalgia.<\/p>\n<p><a href=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/07\/the_floating_record-590x330.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-3893 aligncenter\" src=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/07\/the_floating_record-590x330-300x168.jpg\" alt=\"the_floating_record-590x330\" width=\"361\" height=\"202\" srcset=\"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/07\/the_floating_record-590x330-300x168.jpg 300w, https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/07\/the_floating_record-590x330.jpg 590w\" sizes=\"auto, (max-width: 361px) 100vw, 361px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.kickstarter.com\/projects\/gramovox\/floating-recordtm-vertical-turntable?ref=video\" target=\"_blank\">Para informarse mas del tema y ver los videos de presentaci\u00f3n del <em>Floating Record<\/em><\/a><\/p>\n<p><a href=\"http:\/\/tn.com.ar\/tecno\/f5\/gramovox-el-primer-gramofono-bluetooth_543883\" target=\"_blank\">Para curiosos: Gramovox, el primer gram\u00f3fono con bluetooh<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se hablo de lo que es un LP, de como se crea y que tipos existen. En este posteo voy a hablar del tocadiscos, que al fin y al cabo, es el que le da vida a los tan mencionados Discos de Vinilo.<\/p>\n","protected":false},"author":67,"featured_media":3887,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[20],"tags":[],"class_list":["post-3866","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vinilo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/07\/c00b46f8736123bfefc5addb4ccba7b3_original.png","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6gfAF-10m","_links":{"self":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/posts\/3866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/users\/67"}],"replies":[{"embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/comments?post=3866"}],"version-history":[{"count":7,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/posts\/3866\/revisions"}],"predecessor-version":[{"id":3912,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/posts\/3866\/revisions\/3912"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/media\/3887"}],"wp:attachment":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/media?parent=3866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/categories?post=3866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/tags?post=3866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}