{"id":3771,"date":"2015-06-25T16:31:54","date_gmt":"2015-06-25T16:31:54","guid":{"rendered":"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/?p=3771"},"modified":"2015-06-25T17:55:57","modified_gmt":"2015-06-25T17:55:57","slug":"amor-por-lo-viejo-mera-nostalgia","status":"publish","type":"post","link":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/amor-por-lo-viejo-mera-nostalgia\/","title":{"rendered":"Amor por lo viejo: \u00bfmera nostalgia?"},"content":{"rendered":"<p>Los \u00e1mbitos <em>indie<\/em>, lo <em>under<\/em>, all\u00ed donde lo comercial o masivo no premia y donde los miedos suelen esfumarse para dar paso a la experimentaci\u00f3n y el disfrute personal en su estado m\u00e1s sincero. Quiz\u00e1s es all\u00ed donde surgen y resurgen los estilos m\u00e1s particulares e interesantes. Quiz\u00e1s es esa misma actitud lo que dio lugar a este nuevo <em>boom<\/em> del vinilo: animarse a dejar de lado lo que se espera ver y rescatar aquello que nunca termin\u00f3 de perderse del todo.<\/p>\n<p>Es as\u00ed c\u00f3mo en los \u00faltimos a\u00f1os surgen todo tipo de movimientos y expresiones art\u00edsticas con fuerte base en tiempos pasados.\u00a0 G\u00e9neros como el Steampunk, juegos con arte pixelado, grupos recreacionistas medievales, dibujos animados como <em>Adventure Time<\/em> o <em>Regular Show, <\/em><strong>vinilos\u2026<\/strong> Cosas que otros ven y dir\u00edan: \u2014 <em>Nadie har\u00eda eso hoy en d\u00eda <\/em>\u2014. Y a\u00fan as\u00ed, muchos lo hacen.<\/p>\n<p><a href=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/06\/Jim-Vinyl.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3787 size-medium\" title=\"Jim Guthrie - Sword &amp; Sworcery LP\" src=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/06\/Jim-Vinyl-300x201.jpg\" alt=\"Jim Guthrie - Sword &amp; Sworcery LP\" width=\"300\" height=\"201\" srcset=\"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/06\/Jim-Vinyl-300x201.jpg 300w, https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/06\/Jim-Vinyl-1024x686.jpg 1024w, https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/06\/Jim-Vinyl.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Por ejemplo, desde hace ya un tiempo que en varias partes del mundo m\u00fasicos y compositores se dedican una vez m\u00e1s al desarrollo de <em>chiptunes<\/em> (m\u00fasica com\u00fanmente generalizada como \u201c8-bits\u201d). Este tipo de m\u00fasica es sintetizada en tiempo real por el chip de sonido de viejas consolas de videojuegos y ordenadores, como la GameBoy, la Commodore 64 o el Family. Sus ruidos y sonidos son sumamente particulares e interesantes, pero lamentablemente suelen ser asociados \u00fanicamente a un g\u00e9nero de \u201cvideojuegos retro\u201d, infantil, de baja calidad, sin real valor musical. Por suerte (y al igual que todos los ejemplos dados), a\u00fan hay gente que puede apreciar su verdadero valor y poco a poco va haciendo crecer el \u00e1mbito al que pertenecen.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-3771-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/06\/Bossfight-Milky-Ways.mp3?_=1\" \/><a href=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/06\/Bossfight-Milky-Ways.mp3\">http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/06\/Bossfight-Milky-Ways.mp3<\/a><\/audio>\n<p>Y es que, al fin y al cabo, \u00bfqu\u00e9 es la calidad? \u00bfLa cantidad de p\u00edxeles que entran en una pantalla? \u00bfM\u00e1s es mejor? <em>M\u00e1s tecnolog\u00eda no equivale a mejor calidad percibida, hay muchos factores en juego. <\/em>La nostalgia sin duda tiene su dosis. Despu\u00e9s de todo, muchos crecieron cuando algunas de estas cosas estaban de moda. Sin embargo, eso no quita que su valor t\u00e9cnico y expresivo sea equiparable a cualquier otro tipo de manifestaci\u00f3n moderna.<\/p>\n<p>Estamos viviendo un boom de la industria independiente. Plataformas de crowdfunding como Kickstarter o Indiegogo permiten a estos grupos reducidos financiar sus proyectos que de otra forma una empresa grande jam\u00e1s se arriesgar\u00eda a producir, o al menos no con la libertad suficiente.<\/p>\n<p><a href=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/06\/Pixel-ejemplo-2-HyperlightDrifter.gif\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3780 size-medium\" title=\"Hyper Light Drifter - Videojuego en desarrollo\" src=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/06\/Pixel-ejemplo-2-HyperlightDrifter-300x170.gif\" alt=\"Hyper Light Drifter - videojuego en desarrollo\" width=\"300\" height=\"170\" \/><\/a><\/p>\n<p>Voy a introducir un t\u00e9rmino que le\u00ed en un <em><a href=\"http:\/\/www.polygon.com\/2015\/5\/13\/8595963\/a-pixel-artist-renounces-pixel-art\" target=\"_blank\">art\u00edculo<\/a><\/em>\u00a0muy interesante que habla sobre el paso del arte 2D a 3D en los videojuegos, y c\u00f3mo el primero se fue volviendo obsoleto. Este t\u00e9rmino es el \u201c<em>fetichismo por lo HD<\/em>\u201d. La sociedad consumista nos impone que todo avance debe estar orientado cada vez m\u00e1s y m\u00e1s hacia un realismo y tecnolog\u00edas mayores, hacia un \u201cprogreso\u201d. Sucede con todo aparato tecnol\u00f3gico del mercado.<\/p>\n<p>A\u00fan as\u00ed, un reducido pero creciente p\u00fablico sigue optando por un tipo de arte de \u201cbaja calidad\u201d, \u201cpixelado\u201d (t\u00e9rmino muchas veces usado despectivamente), un tipo de arte rodeado de prejuicios pero que est\u00e1 teniendo un <em>revival<\/em> similar al asunto que nos ata\u00f1e, el vinilo. \u00bfEs un tema econ\u00f3mico? Al contrario, dado que el tiempo, paciencia y conocimiento requeridos para crear (y ni hablar de animar cuadro por cuadro) una pieza de este tipo suele ser mayor a muchas otras t\u00e9cnicas posibles. Pero es en la claridad y el control que te dan dibujar una pieza p\u00edxel por p\u00edxel en donde reside el valor de esta t\u00e9cnica. Es por eso que tantos artistas incre\u00edbles siguen optando por volver a los viejos tiempos pero sin las limitaciones de entonces, para crear nuevamente todo tipo de genialidades.<\/p>\n<p><a href=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/06\/The-hovel-zi-double.gif\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3781 size-medium\" title=\"The hovel - zi double\" src=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/06\/The-hovel-zi-double-300x173.gif\" alt=\"The hovel - zi double\" width=\"300\" height=\"173\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/06\/Kraken-vs-Vikings.gif\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3786 size-medium\" title=\"Kraken vs Vikings - Cure\" src=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/06\/Kraken-vs-Vikings-300x152.gif\" alt=\"Kraken vs Vikings\" width=\"300\" height=\"152\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/06\/Sword-Sworcery.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3783 size-medium\" title=\"Superbrothers: Sword &amp; Sworcery\" src=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/06\/Sword-Sworcery-300x169.jpg\" alt=\"Sword &amp; Sworcery\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/06\/Sword-Sworcery-300x169.jpg 300w, https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/06\/Sword-Sworcery-1024x576.jpg 1024w, https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/06\/Sword-Sworcery.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Es algo que viene pasando c\u00edclicamente y en todos los \u00e1mbitos: pasa en la m\u00fasica, pasa en el arte, en el dise\u00f1o, la vestimenta y el entretenimiento.<\/p>\n<p>Entonces, \u00bfes la vuelta al vinilo una mera nostalgia hacia lo ya vivido? Yo creo que no, que siempre hay lugar para revivir y reinventar\u00a0 valores pasados, seguir explotando el potencial que \u00e9stos tienen y entender c\u00f3mo funcionaban para adaptarlos lo mejor posible a nuestra \u00e9poca.\u00a0<em style=\"line-height: 1.5\">Nostalgia o no, afortunadamente la cultura vuelve a mirar hacia atr\u00e1s antes de mirar al frente.<\/em><\/p>\n<p>&#8212;&#8211;<\/p>\n<p>Imagen destacada: Rider, por <a href=\"http:\/\/www.pixeljoint.com\/p\/6741.htm\" target=\"_blank\">Fool<br \/>\n<\/a>Tema musical: Milky Ways, por <a href=\"http:\/\/bossfightmusic.bandcamp.com\/album\/caps-on-hats-off\" target=\"_blank\">BossFight<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un breve an\u00e1lisis de c\u00f3mo esta tendencia vuelve a incursionar en la sociedad trayendo de regreso un sinf\u00edn de posibilidades por explotar. El vinilo y otras manifestaciones art\u00edsticas.<\/p>\n","protected":false},"author":52,"featured_media":3772,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[20],"tags":[129,127,126,122,123,130,125,128,124],"class_list":["post-3771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vinilo","tag-8-bit","tag-chipmusic","tag-chiptunes","tag-nostalgia","tag-old-school","tag-pasado","tag-pixel-art","tag-retro","tag-viejo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/06\/Fool.png","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6gfAF-YP","_links":{"self":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/posts\/3771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/comments?post=3771"}],"version-history":[{"count":4,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/posts\/3771\/revisions"}],"predecessor-version":[{"id":3788,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/posts\/3771\/revisions\/3788"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/media\/3772"}],"wp:attachment":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/media?parent=3771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/categories?post=3771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/tags?post=3771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}