{"id":3267,"date":"2015-06-15T04:53:29","date_gmt":"2015-06-15T04:53:29","guid":{"rendered":"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/?p=3267"},"modified":"2015-06-18T14:28:14","modified_gmt":"2015-06-18T14:28:14","slug":"una-nueva-generacion-de-vinilos","status":"publish","type":"post","link":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/una-nueva-generacion-de-vinilos\/","title":{"rendered":"Una nueva generaci\u00f3n de vinilos"},"content":{"rendered":"<p>El declive de los discos de vinilo comenz\u00f3 en los a\u00f1os 80, y se fue consolidando a medida que el CD fue asent\u00e1ndose en el mercado. Estos peque\u00f1os discos que conten\u00edan m\u00fasica en formato digital ofrec\u00edan ventajas importantes frente a los vinilos. Una era la ausencia total de ese ruido\u00a0en el proceso de lectura de los discos de vinilo, provocado por el rozamiento de la aguja al deslizarse por los surcos de la superficie del disco, lo que iba arrancando poco a poco material, erosion\u00e1ndolos, y con el tiempo reduc\u00eda la calidad de sonido as\u00ed como la vida \u00fatil de \u00e9stos y de la aguja misma. \u00a0Las primeras producciones y lectores de CD no eran perfectos, pero, lograron conquistar al<a class=\"edvkyazyd\" title=\"Click to Continue &gt; by PhraseFinder\" href=\"#91033491\"> nuevo<img decoding=\"async\" src=\"http:\/\/cdncache-a.akamaihd.net\/items\/it\/img\/arrow-10x10.png\" alt=\"\" \/><\/a> p\u00fablico por\u00a0su sonido limpio\u00a0y por lo c\u00f3modo de su reproducci\u00f3n.<\/p>\n<p>Probablemente el mercado de los discos de vinilo nunca volver\u00e1 a tener las dimensiones que tuvo, pero ha recuperado la suficiente fuerza para revivir una industria que parec\u00eda condenada al olvido. Y es por que, hoy en d\u00eda podemos encontrar en las tiendas una gran variedad de estos\u00a0discos que no son otra cosa que peque\u00f1as obras de ingenier\u00eda. Lo interesante es que este formato ha evolucionado mucho desde un punto de vista tecnol\u00f3gico\u00a0lo que<a class=\"edvkyazyd\" title=\"Click to Continue &gt; by PhraseFinder\" href=\"#16010245\"> ayud\u00f3<img decoding=\"async\" src=\"http:\/\/cdncache-a.akamaihd.net\/items\/it\/img\/arrow-10x10.png\" alt=\"\" \/><\/a> a que las desventajas queden difuminadas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3268\" src=\"http:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/06\/0001330284_10-300x284.jpg\" alt=\"0001330284_10\" width=\"300\" height=\"284\" srcset=\"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/06\/0001330284_10-300x284.jpg 300w, https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/06\/0001330284_10-1024x969.jpg 1024w, https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/06\/0001330284_10.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Hace unos a\u00f1os, en nuestro pa\u00eds,\u00a0tres j\u00f3venes unidos por la m\u00fasica lanzaron un sello, <strong>Hallo Discos<\/strong>,\u00a0que edita exclusivamente en vinilo.\u00a0Los responsables de este peque\u00f1o paso para el hombre mel\u00f3mano, Jos\u00e9 Dagostino, Gast\u00f3n Cutica y Hern\u00e1n Literas, decidieron cumplir el sue\u00f1o del vinilo propio. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 <em>\u00abNos pusimos a investigar por<a class=\"edvkyazyd\" title=\"Click to Continue &gt; by PhraseFinder\" href=\"#88926195\"> Internet<img decoding=\"async\" src=\"http:\/\/cdncache-a.akamaihd.net\/items\/it\/img\/arrow-10x10.png\" alt=\"\" \/><\/a> c\u00f3mo pod\u00edamos hacer para editar disco en vinilo y luego de pasar por varios foros sobre el tema terminamos encontrando a un tornero alem\u00e1n que hab\u00eda fabricado una m\u00e1quina para grabar vinilos de a uno. Eso s\u00ed, no te la vend\u00eda si no viajabas hasta su casa y hac\u00edas con \u00e9l un curso de un d\u00eda para aprender a usar la m\u00e1quina\u00bb &#8211;<\/em>cuenta Gast\u00f3n Cutica.<\/p>\n<p>Hallo Discos<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los discos de vinilo est\u00e1n volviendo. Basta darse un paseo por alguna de las grandes superficies comerciales en las que se vende m\u00fasica para encontrarlos.<\/p>\n","protected":false},"author":27,"featured_media":3269,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[20],"tags":[68,69,67],"class_list":["post-3267","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vinilo","tag-hallo-discos","tag-musica","tag-vinilo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-content\/uploads\/2015\/06\/discos-vinilo-moda-1.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6gfAF-QH","_links":{"self":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/posts\/3267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/comments?post=3267"}],"version-history":[{"count":6,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/posts\/3267\/revisions"}],"predecessor-version":[{"id":3521,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/posts\/3267\/revisions\/3521"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/media\/3269"}],"wp:attachment":[{"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/media?parent=3267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/categories?post=3267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.catedracosgaya.com.ar\/tipoblog\/2015\/wp-json\/wp\/v2\/tags?post=3267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}